{"id":3256,"date":"2022-07-20T08:39:55","date_gmt":"2022-07-20T06:39:55","guid":{"rendered":"https:\/\/afaescolalamitjana.cat\/ampa\/?page_id=3256"},"modified":"2025-10-03T11:50:47","modified_gmt":"2025-10-03T09:50:47","slug":"extraescolars-2","status":"publish","type":"page","link":"https:\/\/afaescolalamitjana.cat\/ampa\/extraescolars-2\/","title":{"rendered":"EXTRAESCOLARS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3256\" class=\"elementor elementor-3256\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2b90f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2b90f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79ea7de\" data-id=\"79ea7de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfa81f3 elementor-widget elementor-widget-text-editor\" data-id=\"bfa81f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\">Totes les activitats s\u00f3n impartides per professionals especialitzats, dins del seu camp.<\/span><br style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\"><br style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\"><span style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\">Les altes i baixes a les activitats es poden fer presencialment, per correu electr\u00f2nic o tel\u00e8fon.<\/span><br style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\"><br style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\"><span style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\">Des de l\u2019AFA oferim un gran ventall d\u2019activitats de caire art\u00edstic, musical, d&#8217;oci i esportiu.<\/span><br style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\"><span style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\">Es poden dur a terme tant al migdia com a la tarda, a partir de les 16.30h<\/span><br style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\"><br style=\"color: rgb(0, 0, 0); font-family: &quot;Open Sans&quot;; font-size: 15px; background-color: rgb(255, 255, 255);\"><a href=\"https:\/\/afaescolalamitjana.cat\/wp-content\/uploads\/2022\/07\/2014_12_03-Reglament-activitats-extraescolars-14-15-aprovat-per-assemblea-1.pdf\" target=\"_blank\" rel=\"noopener\" style=\"background-color: rgb(255, 255, 255); font-family: &quot;Open Sans&quot;; font-size: 15px;\">Reglament activitats extraescolars<\/a><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e50909 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e50909\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbbc2f3\" data-id=\"dbbc2f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23d76b3 elementor-widget elementor-widget-image\" data-id=\"23d76b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"3758\" data-permalink=\"https:\/\/afaescolalamitjana.cat\/ampa\/extraescolars-2\/1-2025\/\" data-orig-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?fit=873%2C612&amp;ssl=1\" data-orig-size=\"873,612\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1-2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?fit=750%2C526&amp;ssl=1\" width=\"750\" height=\"526\" src=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?fit=750%2C526&amp;ssl=1\" class=\"attachment-large size-large wp-image-3758\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?w=873&amp;ssl=1 873w, https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?resize=300%2C210&amp;ssl=1 300w, https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?resize=768%2C538&amp;ssl=1 768w\" sizes=\"(max-width: 750px) 100vw, 750px\" data-attachment-id=\"3758\" data-permalink=\"https:\/\/afaescolalamitjana.cat\/ampa\/extraescolars-2\/1-2025\/\" data-orig-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?fit=873%2C612&amp;ssl=1\" data-orig-size=\"873,612\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1-2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/1-2025.jpg?fit=750%2C526&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a73fa7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a73fa7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-892cd82\" data-id=\"892cd82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c2ff53 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9c2ff53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"3760\" data-permalink=\"https:\/\/afaescolalamitjana.cat\/ampa\/extraescolars-2\/2-202\/\" data-orig-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?fit=890%2C640&amp;ssl=1\" data-orig-size=\"890,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"2-202\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?fit=750%2C539&amp;ssl=1\" width=\"750\" height=\"539\" src=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?fit=750%2C539&amp;ssl=1\" class=\"attachment-large size-large wp-image-3760\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?w=890&amp;ssl=1 890w, https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?resize=300%2C216&amp;ssl=1 300w, https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?resize=768%2C552&amp;ssl=1 768w\" sizes=\"(max-width: 750px) 100vw, 750px\" data-attachment-id=\"3760\" data-permalink=\"https:\/\/afaescolalamitjana.cat\/ampa\/extraescolars-2\/2-202\/\" data-orig-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?fit=890%2C640&amp;ssl=1\" data-orig-size=\"890,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"2-202\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/2-202.jpg?fit=750%2C539&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cb0f9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cb0f9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bd931a\" data-id=\"2bd931a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce77fbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce77fbc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42b4291\" data-id=\"42b4291\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e21df96 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e21df96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"3761\" data-permalink=\"https:\/\/afaescolalamitjana.cat\/ampa\/extraescolars-2\/preus25\/\" data-orig-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/preus25.jpg?fit=498%2C717&amp;ssl=1\" data-orig-size=\"498,717\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"preus25\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/preus25.jpg?fit=498%2C717&amp;ssl=1\" width=\"498\" height=\"717\" src=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/preus25.jpg?fit=498%2C717&amp;ssl=1\" class=\"attachment-large size-large wp-image-3761\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/preus25.jpg?w=498&amp;ssl=1 498w, https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/preus25.jpg?resize=208%2C300&amp;ssl=1 208w\" sizes=\"(max-width: 498px) 100vw, 498px\" data-attachment-id=\"3761\" data-permalink=\"https:\/\/afaescolalamitjana.cat\/ampa\/extraescolars-2\/preus25\/\" data-orig-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/preus25.jpg?fit=498%2C717&amp;ssl=1\" data-orig-size=\"498,717\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"preus25\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/afaescolalamitjana.cat\/wp-content\/uploads\/2025\/10\/preus25.jpg?fit=498%2C717&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Totes les activitats s\u00f3n impartides per professionals especialitzats, dins del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"class_list":["post-3256","page","type-page","status-publish","hentry"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Administrador","author_link":"https:\/\/afaescolalamitjana.cat\/ampa\/author\/administrador\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Totes les activitats s\u00f3n impartides per professionals especialitzats, dins del [&hellip;]","_links":{"self":[{"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/pages\/3256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/comments?post=3256"}],"version-history":[{"count":21,"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/pages\/3256\/revisions"}],"predecessor-version":[{"id":3767,"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/pages\/3256\/revisions\/3767"}],"wp:attachment":[{"href":"https:\/\/afaescolalamitjana.cat\/ampa\/wp-json\/wp\/v2\/media?parent=3256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}